{"id":11963,"count":1,"description":"","link":"https:\/\/revistaempresarios.net\/web\/tag\/energia-solar-ja-sustenta-cadeia-consolidada-de-empregos-no-brasil-e-reforca-eficiencia-do-setor-eletrico\/","name":"Energia solar j\u00e1 sustenta cadeia consolidada de empregos no Brasil e refor\u00e7a efici\u00eancia do setor el\u00e9trico","slug":"energia-solar-ja-sustenta-cadeia-consolidada-de-empregos-no-brasil-e-reforca-eficiencia-do-setor-eletrico","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags\/11963"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts?tags=11963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}