{"id":9930,"date":"2023-06-19T21:21:26","date_gmt":"2023-06-20T00:21:26","guid":{"rendered":"https:\/\/revistaempresarios.net\/web\/?p=9930"},"modified":"2023-06-19T21:21:26","modified_gmt":"2023-06-20T00:21:26","slug":"medalhistas-olimpicos-empresarios-e-investidores-participam-de-forum-de-alta-performance-em-sao-paulo","status":"publish","type":"post","link":"https:\/\/revistaempresarios.net\/web\/2023\/06\/19\/medalhistas-olimpicos-empresarios-e-investidores-participam-de-forum-de-alta-performance-em-sao-paulo\/","title":{"rendered":"Medalhistas ol\u00edmpicos, empres\u00e1rios e investidores participam de f\u00f3rum de alta performance em S\u00e3o Paulo"},"content":{"rendered":"<p class=\"fst-italic text-center\">Esporte e neg\u00f3cios se conectam no f\u00f3rum realizado pela matter&amp;Co. Evento ser\u00e1 realizado no dia 4 de julho, no Hotel Pullman Vila Ol\u00edmpia<\/p>\n<div>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/files.pressmanager.net\/clientes\/93c567ec31d8a30599ded0af85095c82\/imagens\/2023\/06\/19\/89e0f5ebe34cac1f9be66fd3c8621ea1_medium.jpg\" alt=\"\" width=\"300\" height=\"167\" \/><\/p>\n<p>Em breve,\u00a0<strong>S\u00e3o Paulo<\/strong>\u00a0receber\u00e1 o evento corporativo\u00a0<strong><em>Fazendo a Diferen\u00e7a: F\u00f3rum de Alta Performance<\/em><\/strong>, que visa reunir empres\u00e1rios e executivos interessados em estrat\u00e9gias de alta performance nos neg\u00f3cios. Entre os speakers est\u00e3o atletas de sucesso, como os medalhistas ol\u00edmpicos\u00a0<strong>Gustavo Borges, T\u00e9o Laborne<\/strong>\u00a0e\u00a0<strong>Fernando Scherer<\/strong>, e\u00a0<strong>Carlos Aldan<\/strong>, membro do Conselho Consultivo da Harvard Business Review.<\/p>\n<p>O evento ser\u00e1 realizado pela\u00a0<strong>matter&amp;Co.<\/strong>, no dia\u00a0<strong>4 de julho<\/strong>, das\u00a0<strong>18h \u00e0s 23h<\/strong>, no\u00a0<strong>Hotel Pullman Vila Ol\u00edmpia<\/strong>, de f\u00e1cil acesso aos aeroportos de Guarulhos e Congonhas e pr\u00f3ximo ao polo de neg\u00f3cios da Av. Faria Lima. Os mediadores ser\u00e3o\u00a0<strong>Roque Almeida<\/strong>, CEO-founder da matter&amp;Co, e\u00a0<strong>Carol Gilberti<\/strong>, jornalista, investidora e empreendedora. As inscri\u00e7\u00f5es podem ser feitas\u00a0no site\u00a0<a href=\"http:\/\/www.fazendoadiferenca.co\/\">www.fazendoadiferenca.co<\/a>. .<\/p>\n<p><em>\u201cO\u00a0<\/em>F\u00f3rum de Alta Performance<em>\u00a0\u00e9 uma oportunidade \u00fanica de encontro com o Carlos Aldan, que \u00e9 refer\u00eancia internacional em Intelig\u00eancia Emocional, e cinco grandes atletas brasileiros, conduzidos pela expertise da Carol Gilberti na media\u00e7\u00e3o das conversas. Teremos, inclusive, dois momentos exclusivamente voltados para o networking, no coffee de recep\u00e7\u00e3o e no coquetel de encerramento. Nosso objetivo \u00e9 aprimorar as habilidades profissionais e impulsionar os neg\u00f3cios de todos os participantes\u201d<\/em>, comenta o CEO da matter&amp;Co.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/files.pressmanager.net\/clientes\/93c567ec31d8a30599ded0af85095c82\/imagens\/2023\/06\/19\/7936dfdcd6bac7d4cd8611d0e82e7266_medium.jpg\" alt=\"\" width=\"300\" height=\"450\" \/><\/p>\n<p>A matter&amp;Co. tem se destacado por oferecer solu\u00e7\u00f5es eficazes para empresas que buscam melhorar sua produtividade e desempenho. O F\u00f3rum de Alta Performance \u00e9 uma iniciativa instigante para as mais diversas organiza\u00e7\u00f5es. Fazendo uma analogia entre atletas e empreendedores, o evento mostra como no mundo dos neg\u00f3cios \u00e9 poss\u00edvel alcan\u00e7ar resultados excepcionais com base nos mesmos princ\u00edpios do esporte profissional.<\/p>\n<p>A matter&amp;Co. \u00e9 um ecossistema de empresas de intelig\u00eancia de neg\u00f3cios. O grupo, que re\u00fane empresas com servi\u00e7os e produtos complementares com mais de 25 anos de experi\u00eancia de mercado, desenvolve empresas e empreendedores para enfrentar os desafios do presente e construir o futuro por meio dos pilares organiza\u00e7\u00e3o, m\u00e9todo, prop\u00f3sito e inova\u00e7\u00e3o. As empresas do grupo s\u00e3o\u00a0<strong>Smart Business Lab<\/strong>, consultoria em estrat\u00e9gia e gest\u00e3o de neg\u00f3cios,\u00a0<strong>Jumppi<\/strong>, empresa de pesquisa e intelig\u00eancia,\u00a0<strong>beePO<\/strong>,\u00a0especialista em gest\u00e3o financeira de neg\u00f3cios,\u00a0<strong>Umanse<\/strong>,\u00a0recrutadora de talentos e Desenvolvimento de times de alta performance,\u00a0<strong>IN3<\/strong>, empresa de ci\u00eancia e an\u00e1lise de dados,\u00a0<strong>GO!NTELLIGENCE<\/strong>, consultoria de intelig\u00eancia de mercado e\u00a0<strong>Calebe_<\/strong>, empresa de branding e produtos digitais.<\/p>\n<p><strong>Primeiro recorde mundial da nata\u00e7\u00e3o brasileira<\/strong><\/p>\n<p>No mesmo dia do evento, os atletas e palestrantes\u00a0<strong>Gustavo Borges, T\u00e9o Laborne<\/strong>\u00a0e\u00a0<strong>Fernando Scherer\u00a0<\/strong>tamb\u00e9m celebram o primeiro recorde mundial da nata\u00e7\u00e3o brasileira por equipes de piscina curta no revezamento 4&#215;100, que completa 30 anos. Os tr\u00eas recordistas, junto a Jos\u00e9 Carlos J\u00fanior, conquistaram o feito no Clube Internacional de Regatas (Santos), no Trof\u00e9u Jos\u00e9 Finkel. Para n\u00e3o deixar passar em branco o anivers\u00e1rio dessa conquista, um evento de comemora\u00e7\u00e3o acontece no dia 4 de julho de 2023, \u00e0s 9h30, no mesmo local em que o recorde foi quebrado em 1993. Na ocasi\u00e3o haver\u00e1 o lan\u00e7amento do Instituto Teo Laborne. Uma institui\u00e7\u00e3o que tem como foco crian\u00e7as e jovens em vulnerabilidade social.<\/p>\n<p><strong>Programa\u00e7\u00e3o<\/strong><\/p>\n<p><strong>18h | Recep\u00e7\u00e3o<\/strong><\/p>\n<p>Coffee e networking<\/p>\n<p><strong>19h | Abertura<\/strong><\/p>\n<p><strong>Media\u00e7\u00e3o de Roque Almeida e Carol Gilberti<\/strong><\/p>\n<p>Roque Almeida \u00e9 CEO-Founder do grupo matter&amp;Co. e investidor anjo de startups de tecnologia. Graduado em Administra\u00e7\u00e3o, tem especializa\u00e7\u00e3o em Finan\u00e7as, MBA em Gest\u00e3o de Projetos e mestrado em Estrat\u00e9gia.<\/p>\n<p>Carol Gilberti \u00e9 jornalista, colunista da BandNews, fundadora e porta-voz do Mulheres El\u00e9tricas, investidora anjo, s\u00f3cia, idealizadora e CEO da Mubius WomenTech Ventures.<\/p>\n<p><strong>19h20 | Resultado individual ou coletivo?<\/strong><\/p>\n<p><strong>Com Heleno Fortes e B\u00e1rbara Gabriela<\/strong><\/p>\n<p>Heleno Fortes \u00e9 um treinador campe\u00e3o sul-americano de meia maratona e j\u00e1 correu 24 maratonas sub 3h. Fundou a Heleno Fortes Treinamento Esportivo para ajudar pessoas a melhorarem a qualidade de vida com a corrida. Heleno vai debater sobre desenvolvimento individual.<\/p>\n<p>B\u00e1rbara Gabriela \u00e9 m\u00e9dica p\u00f3s-graduada em Endocrinologia e em Nutrologia, al\u00e9m de ultramaratonista. Ela faz da paix\u00e3o pelo esporte o seu trabalho, atendendo atletas amadores e de alta performance.<\/p>\n<p><strong>20h | Resili\u00eancia e Determina\u00e7\u00e3o<\/strong><\/p>\n<p><strong>Com Carlos Aldan<\/strong><\/p>\n<p>Carlos Aldan \u00e9 membro do Conselho Consultivo da Harvard Business Review e CEO do Grupo Kronberg. O executivo construiu sua carreira internacional \u00e0 frente de organiza\u00e7\u00f5es como o World Trade Center.<\/p>\n<p><strong>20h45 | Coopera\u00e7\u00e3o em Alta Performance<\/strong><\/p>\n<p><strong>Com T\u00e9o Laborne, Gustavo Borges e Fernando Scherer<\/strong><\/p>\n<p>Os tr\u00eas recordistas brasileiros, que estar\u00e3o comemorando os 30 anos de seu recorde mundial em nata\u00e7\u00e3o, v\u00e3o debater a alta performance associada ao esp\u00edrito colaborativo e ao trabalho em equipe.<\/p>\n<p><strong>21h30 &#8211; 23h | Encerramento<\/strong><\/p>\n<p>Coquetel e networking<\/p>\n<p><strong>Servi\u00e7o<\/strong><\/p>\n<p><strong>matter&amp;Co. apresenta\u00a0<\/strong><strong><em>Fazendo a Diferen\u00e7a: F\u00f3rum de Alta Performance<\/em><\/strong><\/p>\n<p>4 de julho, das 18h \u00e0s 23h<\/p>\n<p>Hotel Pullman Vila Ol\u00edmpia<\/p>\n<ol>\n<li>Olimp\u00edadas, 205 &#8211; Vila Ol\u00edmpia, S\u00e3o Paulo &#8211; SP, 04551-000<\/li>\n<\/ol>\n<p>Inscri\u00e7\u00f5es e informa\u00e7\u00f5es: www.fazendoadiferenca.co<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esporte e neg\u00f3cios se conectam no f\u00f3rum realizado pela matter&amp;Co. Evento ser\u00e1 realizado no dia 4 de julho, no Hotel Pullman Vila Ol\u00edmpia Em breve,\u00a0S\u00e3o Paulo\u00a0receber\u00e1 o evento corporativo\u00a0Fazendo a Diferen\u00e7a: F\u00f3rum de Alta Performance, que visa reunir empres\u00e1rios e executivos interessados em estrat\u00e9gias de alta performance nos neg\u00f3cios. Entre os speakers est\u00e3o atletas de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[51,56,58,60],"tags":[7627,7626],"featured_image_src":{"landsacpe":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/89e0f5ebe34cac1f9be66fd3c8621ea1_medium.jpg",300,167,false],"list":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/89e0f5ebe34cac1f9be66fd3c8621ea1_medium.jpg",300,167,false],"medium":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/89e0f5ebe34cac1f9be66fd3c8621ea1_medium.jpg",300,167,false],"full":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/89e0f5ebe34cac1f9be66fd3c8621ea1_medium.jpg",300,167,false]},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/89e0f5ebe34cac1f9be66fd3c8621ea1_medium.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/9930"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/comments?post=9930"}],"version-history":[{"count":1,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/9930\/revisions"}],"predecessor-version":[{"id":9932,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/9930\/revisions\/9932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media\/9931"}],"wp:attachment":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media?parent=9930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/categories?post=9930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags?post=9930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}