{"id":9718,"date":"2023-06-15T10:43:17","date_gmt":"2023-06-15T13:43:17","guid":{"rendered":"https:\/\/revistaempresarios.net\/web\/?p=9718"},"modified":"2023-06-15T10:44:45","modified_gmt":"2023-06-15T13:44:45","slug":"as-principais-duvidas-contratuais-dos-empreendedores-testemunhas-confidencialidade-regime-pj-ou-clt","status":"publish","type":"post","link":"https:\/\/revistaempresarios.net\/web\/2023\/06\/15\/as-principais-duvidas-contratuais-dos-empreendedores-testemunhas-confidencialidade-regime-pj-ou-clt\/","title":{"rendered":"As principais d\u00favidas contratuais dos empreendedores: Testemunhas, confidencialidade, regime PJ ou CLT"},"content":{"rendered":"<div class=\"itemBody\">\n<div class=\"itemIntroText\">\n<p>Assessoria jur\u00eddica e formaliza\u00e7\u00e3o do contrato auxilia micro, pequenas e m\u00e9dia empresas<\/p>\n<\/div>\n<div class=\"itemFullText\">\n<p>Uma assessoria jur\u00eddica especializada \u00e9 essencial para que a elabora\u00e7\u00e3o de contratos empresariais esteja em conformidade com a legisla\u00e7\u00e3o vigente, para a prote\u00e7\u00e3o dos interesses comerciais e com o objetivo de evitar conflitos, resolver disputas e servir como aux\u00edlio para negocia\u00e7\u00f5es mais eficazes.<\/p>\n<p>Cada neg\u00f3cio \u00e9 \u00fanico e, por isso, os advogados devem fazer contratos personalizados com as adapta\u00e7\u00f5es que s\u00e3o necess\u00e1rias para cada tipo de contrato, levando em conta a natureza e especifica\u00e7\u00f5es do empreendimento. Com contratos que mitigam os riscos, direitos e obriga\u00e7\u00f5es ficam mais claros para todas as partes envolvidas.<\/p>\n<p>A formaliza\u00e7\u00e3o de contratos empresariais e trabalhistas requerem a busca por um advogado de confian\u00e7a, visando a garantia da prote\u00e7\u00e3o legal da empresa, reduzindo de forma significativa os riscos de potenciais lit\u00edgios. \u201cAl\u00e9m disso, um contrato elaborado da forma correta auxilia no estabelecimento de rela\u00e7\u00f5es comerciais s\u00f3lidas, trazendo benef\u00edcios para o contratante e para a parte contratada\u201d, <strong>destaca a advogada Roberta Von Jelita<\/strong>. Pensando nisso, a s\u00f3cia do Escrit\u00f3rio de Advocacia RVJ, orienta empreendedores sobre as principais d\u00favidas na hora de formalizar documentos contratuais.<\/p>\n<p><strong>Assinaturas de testemunhas no contrato<\/strong><\/p>\n<p>Um dos principais problemas dos contratos empresariais e de presta\u00e7\u00e3o de servi\u00e7os \u00e9 a falta da assinatura de duas testemunhas, constando somente a empresa e fornecedor, ou empresa e cliente.<\/p>\n<p>De acordo com a advogada, o empres\u00e1rio precisa da assinatura de duas testemunhas em contratos de presta\u00e7\u00e3o de servi\u00e7o. \u201cO empres\u00e1rio poder\u00e1 encarar uma batalha judicial desnecess\u00e1ria e com isso perder dinheiro em seu neg\u00f3cio, caso um cliente deixe de pagar ou caso o fornecedor perca o prazo de entrega e n\u00e3o constar as assinaturas das testemunhas no contrato firmado entre as partes\u201d, alerta a advogada, citando o exemplo de a\u00e7\u00f5es de execu\u00e7\u00e3o.<\/p>\n<p><strong>Cl\u00e1usula sobre confidencialidade e divulga\u00e7\u00e3o<\/strong><\/p>\n<p>A cl\u00e1usula de confidencialidade \u00e9 um meio de prote\u00e7\u00e3o jur\u00eddica que se estende a pessoas f\u00edsicas ou jur\u00eddicas e consiste em uma restri\u00e7\u00e3o prevista em contratos, que pro\u00edbe o repasse de informa\u00e7\u00f5es confidenciais de acesso entre as partes.<\/p>\n<p>\u201cPara ficar mais claro, as partes podem divulgar nas redes sociais e sites que determinada pessoa \u00e9 cliente, entre outros. \u00c9 poss\u00edvel divulgar o servi\u00e7o prestado, como no caso de projetos e obras de arquitetos. No entanto, o que fica determinado como confidencial precisa ser mantido sob sigilo\u201d, compara Roberta Von Jelita.<\/p>\n<p><strong>Detalhes contratuais<\/strong><\/p>\n<p>O contrato pode ser celebrado entre duas pessoas jur\u00eddicas ou entre uma empresa e uma pessoa f\u00edsica, ou com fornecedor ou consumidor.<\/p>\n<p>Os contratos podem ser de m\u00e3o-de-obra, como de trabalho ou de presta\u00e7\u00e3o de servi\u00e7os, ou at\u00e9 de insumos, como fornecimento de energia ou mat\u00e9rias-primas, loca\u00e7\u00e3o, arrendamento, parcerias, tecnologia, distribui\u00e7\u00e3o, franquia, representa\u00e7\u00e3o comercial e diversas outras possibilidades.<\/p>\n<p>\u201cOs instrumentos jur\u00eddicos realizados pela ou com a empresa precisam ser cuidadosamente negociados e seguir pol\u00edticas internas para que estejam de acordo com as finalidades das organiza\u00e7\u00f5es\u201d, destaca a advogada.<\/p>\n<p>\u00c9 preciso identificar quais as partes envolvidas, com nome, endere\u00e7o, CNPJ e outras informa\u00e7\u00f5es relevantes. Al\u00e9m disso, est\u00e3o entre as principais cl\u00e1usulas o objeto do contrato, o prazo, valor e forma de pagamento, assim como responsabilidades das partes e consequ\u00eancias de descumprimento das obriga\u00e7\u00f5es. Mecanismos de propriedade intelectual como patentes e direitos autorais tamb\u00e9m devem ser estabelecidos e bem delimitados.<\/p>\n<p><strong>Contrata\u00e7\u00e3o PJ ou CLT<\/strong><\/p>\n<p>Muitas empresas buscam contratar colaboradores como pessoa jur\u00eddica com o objetivo de diminuir a incid\u00eancia de tributos. No entanto, a advogada orienta que, na pr\u00e1tica, se a atua\u00e7\u00e3o for como funcion\u00e1rio, o empregador tende a gastar ainda mais com a\u00e7\u00f5es trabalhistas.<\/p>\n<p>\u201cSe na pr\u00e1tica, o funcion\u00e1rio atua como seria um CLT, a empresa vai gastar mais com a a\u00e7\u00e3o trabalhista do que com os impostos que pagaria. Se \u00e9 PJ contrata PJ, se \u00e9 CLT contrata CLT\u201d, alerta a advogada.<\/p>\n<p>Alguns requisitos determinam um v\u00ednculo trabalhista, quando a contrata\u00e7\u00e3o formal deve ser realizada. \u201cSe h\u00e1 pessoalidade, ou somente aquela pessoa pode fazer o trabalho, se h\u00e1 carga hor\u00e1ria e dias definidos para o desenvolvimento das tarefas, se o colaborador recebe um sal\u00e1rio fixo ou h\u00e1 subordina\u00e7\u00e3o, a contrata\u00e7\u00e3o deve ser pelo regime CLT\u201d, refor\u00e7a a Roberta Von Jelita.<\/p>\n<p>No caso de uma pessoa jur\u00eddica, a empresa n\u00e3o pode obrigar uma carga hor\u00e1ria definida ou que bata ponto, pagar gratifica\u00e7\u00f5es, exigir subordina\u00e7\u00e3o, nem fornecer e-mail corporativo.<\/p>\n<\/div>\n<\/div>\n<div class=\"e-mailit_toolbox circular size48\">\n<div class=\"e-mailit_btn_EMAILiT\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Assessoria jur\u00eddica e formaliza\u00e7\u00e3o do contrato auxilia micro, pequenas e m\u00e9dia empresas Uma assessoria jur\u00eddica especializada \u00e9 essencial para que a elabora\u00e7\u00e3o de contratos empresariais esteja em conformidade com a legisla\u00e7\u00e3o vigente, para a prote\u00e7\u00e3o dos interesses comerciais e com o objetivo de evitar conflitos, resolver disputas e servir como aux\u00edlio para negocia\u00e7\u00f5es mais eficazes. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"featured_image_src":{"landsacpe":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/f49d3d452b9ad566f99614ca42a334ce_XL-1140x445.jpg",1140,445,true],"list":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/f49d3d452b9ad566f99614ca42a334ce_XL-463x348.jpg",463,348,true],"medium":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/f49d3d452b9ad566f99614ca42a334ce_XL-300x200.jpg",300,200,true],"full":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/f49d3d452b9ad566f99614ca42a334ce_XL.jpg",1220,813,false]},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/06\/f49d3d452b9ad566f99614ca42a334ce_XL.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/9718"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/comments?post=9718"}],"version-history":[{"count":1,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/9718\/revisions"}],"predecessor-version":[{"id":9720,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/9718\/revisions\/9720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media\/9719"}],"wp:attachment":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media?parent=9718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/categories?post=9718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags?post=9718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}