{"id":21358,"date":"2026-04-13T20:55:59","date_gmt":"2026-04-13T23:55:59","guid":{"rendered":"https:\/\/revistaempresarios.net\/web\/?p=21358"},"modified":"2026-04-13T20:55:59","modified_gmt":"2026-04-13T23:55:59","slug":"voce-quer-gerar-resultado-ou-so-cobrar-resultado","status":"publish","type":"post","link":"https:\/\/revistaempresarios.net\/web\/2026\/04\/13\/voce-quer-gerar-resultado-ou-so-cobrar-resultado\/","title":{"rendered":"Voc\u00ea quer gerar resultado ou s\u00f3 cobrar resultado?"},"content":{"rendered":"<p><i>Reinaldo Rachid mostra em livro por que o maior gargalo das empresas n\u00e3o est\u00e1 na estrat\u00e9gia, mas na forma como as pessoas s\u00e3o lideradas<\/i><\/p>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2026\/04\/13\/cfbbda6d100e60687df80df7198ec7a8_medium.jpg\" width=\"200\" align=\"left\" hspace=\"10\" \/>Em um cen\u00e1rio empresarial marcado por press\u00e3o por desempenho, acelera\u00e7\u00e3o tecnol\u00f3gica e queda nos n\u00edveis de engajamento, uma pergunta essencial ganha for\u00e7a: por que empresas com boas estrat\u00e9gias continuam falhando na execu\u00e7\u00e3o? Para o engenheiro, consultor e escritor\u00a0<strong>Reinaldo Rachid<\/strong>, o problema raramente est\u00e1 na estrat\u00e9gia, mas sim na forma como as pessoas s\u00e3o conduzidas dentro das organiza\u00e7\u00f5es.<\/p>\n<p>Essa \u00e9 a provoca\u00e7\u00e3o central do livro\u00a0<strong>Gerar valor com pessoas<\/strong>, publicado pela editora\u00a0<strong>Actual<\/strong>, do Grupo Editorial Alta Books. Na obra, Rachid prop\u00f5e uma mudan\u00e7a de paradigma na gest\u00e3o. Segundo ele, \u00e9 preciso sair de modelos fortemente estruturados em controle e cobran\u00e7a para uma abordagem que conecta cultura, comportamento e resultado. \u201cIdentificar problemas e criar solu\u00e7\u00f5es s\u00e3o a\u00e7\u00f5es muito diferentes e as empresas t\u00eam formado profissionais muito mais para diagnosticar do que para resolver\u201d, afirma o autor.<\/p>\n<p>Com mais de 25 anos de experi\u00eancia em consultoria, Rachid construiu sua vis\u00e3o a partir de um padr\u00e3o recorrente de organiza\u00e7\u00f5es que dominam ferramentas e m\u00e9todos, mas falham na execu\u00e7\u00e3o e n\u00e3o conseguem capturar os resultados planejados. Para ele, o maior equ\u00edvoco da gest\u00e3o moderna foi tratar pessoas como parte do processo e n\u00e3o como a origem do resultado.<\/p>\n<p>\u201cEntregamos metas cada vez mais desafiadoras, mas n\u00e3o desenvolvemos as pessoas para alcan\u00e7\u00e1-las. Depois, cobramos o resultado como se o problema fosse apenas de execu\u00e7\u00e3o\u201d, explica. No lan\u00e7amento, o especialista mostra que o verdadeiro diferencial competitivo n\u00e3o est\u00e1 apenas na estrat\u00e9gia, mas na capacidade de transform\u00e1-la em comportamento no dia a dia, o que depende diretamente da lideran\u00e7a e da cultura organizacional.<\/p>\n<p>Um dos principais conceitos apresentados na obra \u00e9 a evolu\u00e7\u00e3o do consagrado ciclo PDCA (Planejar, Executar, Checar e Atuar Corretivamete) para PDCL, incorporando o pilar Li\u00e7\u00f5es Aprendidas, como eixo central da gest\u00e3o. Na pr\u00e1tica, isso significa substituir ambientes de cobran\u00e7a e exposi\u00e7\u00e3o por contextos de aprendizado e desenvolvimento.<\/p>\n<p>\u201cQuando associamos o erro a culpados, eliminamos a oportunidade de aprendizado. Quando investigamos o processo, desenvolvemos as pessoas\u201d, afirma. Essa mudan\u00e7a altera profundamente a forma como l\u00edderes conduzem equipes e cria ambientes mais seguros, colaborativos e orientados \u00e0 melhoria cont\u00ednua.<\/p>\n<p>Outro ponto central do livro \u00e9 a ideia de que a colabora\u00e7\u00e3o, t\u00e3o valorizada nas empresas, n\u00e3o acontece espontaneamente. Ela precisa ser desenvolvida. Rachid comenta que barreiras como ego, medo de julgamento, rivalidade, arrog\u00e2ncia ainda impedem organiza\u00e7\u00f5es de atingir seu potencial coletivo. \u201cPara se ter diversidade de ideias, n\u00e3o basta juntar pessoas. \u00c9 preciso saber conect\u00e1-las\u201d, defende.<\/p>\n<p>Ao longo da obra, o autor apresenta ferramentas pr\u00e1ticas como o Roteiro de 10 Passos para Gerar Valor, a Equa\u00e7\u00e3o da Confian\u00e7a e o Modelo RAIDHO, que integra autoconhecimento, rela\u00e7\u00e3o com o outro e entrega de valor. \u201cLiderar \u00e9 engajar pessoas em busca de realiza\u00e7\u00e3o pessoal, conectando-as a um objetivo comum em que o valor gerado pelo time \u00e9 maior do que as contribui\u00e7\u00f5es individuais\u201d, comenta.<\/p>\n<p>Mais do que um livro sobre gest\u00e3o,\u00a0<strong>Gerar Valor com Pessoas<\/strong>\u00a0trata-se de um convite \u00e0 transforma\u00e7\u00e3o da forma como empresas se organizam, tomam decis\u00f5es e constroem resultados. Uma leitura ideal para CEOs, executivos, gestores, profissionais de recursos humanos e todos que ocupam ou desejam ocupar posi\u00e7\u00f5es de lideran\u00e7a.<\/p>\n<p>Ao fugir da rigidez dos manuais tradicionais, o lan\u00e7amento funciona como manifesto sobre o futuro das organiza\u00e7\u00f5es e fundamenta a constru\u00e7\u00e3o de ambientes onde pessoas possam assumir responsabilidade, protagonismo e contribui\u00e7\u00e3o real. Com embasamento te\u00f3rico e pr\u00e1tico,\u00a0<strong>Reinaldo Rachid\u00a0<\/strong>refor\u00e7a que o valor das empresas nasce, sobretudo, da qualidade das rela\u00e7\u00f5es humanas que sustentam decis\u00f5es e resultados.<\/p>\n<p><strong>Ficha t\u00e9cnica<\/strong><\/p>\n<p><strong>T\u00edtulo<\/strong>: Gerar valor com pessoas &#8211; Como engajar pessoas, redesenhar a cultura e gerar resultados sustent\u00e1veis em contextos complexos<strong><br \/>\nAutoria<\/strong>: Reinaldo Rachid Jr.<br \/>\n<strong>Editora:<\/strong>\u00a0Actual \/ Grupo Editorial Alta Books<br \/>\n<strong>ISBN:\u00a0978-8562937880<br \/>\nP\u00e1ginas: 108<\/strong><br \/>\n<strong>Pre\u00e7o<\/strong>: R$ 42,90<br \/>\n<strong>Onde encontrar<\/strong>:\u00a0<a href=\"https:\/\/a.co\/d\/021dFUkr\" target=\"_blank\" rel=\"noopener noreferrer\">Amazon<\/a><\/p>\n<p><strong>Sobre o autor<\/strong><\/p>\n<p><strong><img decoding=\"async\" src=\"https:\/\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2026\/04\/13\/5cb77ace9f094b6af8ea6dfb597309d0_medium.jpg\" width=\"150\" align=\"left\" hspace=\"10\" \/>Reinaldo Rachid\u00a0<\/strong>\u00e9 mestre em engenharia qu\u00edmica, escritor e fundador da RAIDHO Consultoria. Com uma trajet\u00f3ria que une performance, cultura e desenvolvimento humano, liderou transforma\u00e7\u00f5es em grandes empresas e hoje atua ao lado de lideran\u00e7as que desejam gerar valor de forma sustent\u00e1vel, humana e respons\u00e1vel. Ao longo de mais de 25 anos de experi\u00eancia, construiu uma abordagem pr\u00f3pria que integra estrat\u00e9gia, protagonismo e gest\u00e3o viva, centrada nas pessoas que fazem.<\/p>\n<p><strong>Redes sociais<\/strong><\/p>\n<p><a href=\"https:\/\/br.linkedin.com\/in\/reinaldorachidjr\" target=\"_blank\" rel=\"noopener noreferrer\">LinkedIn<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.instagram.com\/reinaldo_rachid\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.instagram.com\/raidhoconsultoria\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram RAIDHO<\/a>\u00a0|\u00a0<a href=\"http:\/\/www.raidhoconsultoria.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Site<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Reinaldo Rachid mostra em livro por que o maior gargalo das empresas n\u00e3o est\u00e1 na estrat\u00e9gia, mas na forma como as pessoas s\u00e3o lideradas Em um cen\u00e1rio empresarial marcado por press\u00e3o por desempenho, acelera\u00e7\u00e3o tecnol\u00f3gica e queda nos n\u00edveis de engajamento, uma pergunta essencial ganha for\u00e7a: por que empresas com boas estrat\u00e9gias continuam falhando na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[51,57,60],"tags":[12063],"featured_image_src":{"landsacpe":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2026\/04\/cfbbda6d100e60687df80df7198ec7a8_medium.jpg",300,428,false],"list":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2026\/04\/cfbbda6d100e60687df80df7198ec7a8_medium-300x348.jpg",300,348,true],"medium":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2026\/04\/cfbbda6d100e60687df80df7198ec7a8_medium-210x300.jpg",210,300,true],"full":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2026\/04\/cfbbda6d100e60687df80df7198ec7a8_medium.jpg",300,428,false]},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2026\/04\/cfbbda6d100e60687df80df7198ec7a8_medium.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/21358"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/comments?post=21358"}],"version-history":[{"count":1,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/21358\/revisions"}],"predecessor-version":[{"id":21360,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/21358\/revisions\/21360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media\/21359"}],"wp:attachment":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media?parent=21358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/categories?post=21358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags?post=21358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}