{"id":18961,"date":"2025-06-16T19:29:04","date_gmt":"2025-06-16T22:29:04","guid":{"rendered":"https:\/\/revistaempresarios.net\/web\/?p=18961"},"modified":"2025-06-16T19:29:04","modified_gmt":"2025-06-16T22:29:04","slug":"como-a-natura-pretende-tornar-o-universo-das-startups-mais-diverso-e-inclusivo","status":"publish","type":"post","link":"https:\/\/revistaempresarios.net\/web\/2025\/06\/16\/como-a-natura-pretende-tornar-o-universo-das-startups-mais-diverso-e-inclusivo\/","title":{"rendered":"Como a Natura pretende tornar o universo das startups mais diverso e inclusivo"},"content":{"rendered":"<p class=\"fst-italic text-center\">Empresa estabelece ambi\u00e7\u00f5es e assume o compromisso de investir, por meio do fundo Natura Ventures, em startups lideradas por mulheres, pessoas negras e com diversidade geogr\u00e1fica, al\u00e9m de apoiar solu\u00e7\u00f5es regenerativas<\/p>\n<div>\n<p>\u00a0A Natura, marca l\u00edder em beleza e cuidados pessoais na Am\u00e9rica Latina, est\u00e1 ampliando seus esfor\u00e7os para construir um futuro mais inclusivo e sustent\u00e1vel. Em um novo passo estrat\u00e9gico, a empresa divulga as ambi\u00e7\u00f5es de diversidade para seu fundo de Corporate Venture Capital (CVC), o Natura Ventures. O an\u00fancio fortalece o posicionamento lan\u00e7ado em janeiro, onde a multinacional de cosm\u00e9ticos brasileira reafirma seus compromissos com a regenera\u00e7\u00e3o socioambiental, diversidade e inclus\u00e3o.<\/p>\n<p>Lan\u00e7ado em 2024, o Natura Ventures visa gerar impactos sociais significativos no ecossistema de startups, com foco em solu\u00e7\u00f5es que promovam a regenera\u00e7\u00e3o ambiental e a diversidade. A Natura compromete-se a desenvolver um portf\u00f3lio diversificado, abordando desafios globais como a crise clim\u00e1tica, a inclus\u00e3o de g\u00eanero e a diversidade racial.<\/p>\n<p>Com objetivos claros, o fundo Natura Ventures quer investir em startups comprometidas com a diversidade racial e de g\u00eanero: a meta \u00e9 que 30% das empresas investidas sejam lideradas por mulheres e 15% por pessoas negras (pretas e pardas).<\/p>\n<p>Al\u00e9m disso, h\u00e1, ainda, um olhar para a inclus\u00e3o regional. De acordo com a Associa\u00e7\u00e3o Brasileira de Startups (Abstartups), cerca de 57,6% das startups brasileiras est\u00e3o concentradas no Sudeste. Com o Natura Ventures, a Natura se compromete a assegurar que 10% do portf\u00f3lio do fundo seja composto por empresas sediadas nas regi\u00f5es Norte e Nordeste do Brasil.<\/p>\n<p>A import\u00e2ncia da diversidade nas startups \u00e9 um dos pilares da estrat\u00e9gia do Natura Ventures. De acordo com o IBGE, as mulheres representam mais da metade da popula\u00e7\u00e3o brasileira. No entanto, ao olhar para startups, apenas uma pequena parcela (cerca de 19%) foi fundada exclusivamente por mulheres \u2013 segundo o relat\u00f3rio de 2024 da Associa\u00e7\u00e3o Brasileira de Startups. Al\u00e9m disso, apenas 13,7% dos cargos de lideran\u00e7a no setor de startups s\u00e3o ocupados por mulheres, de acordo com o \u201cStartup Landscape: Lideran\u00e7as Femininas 2024\u201d publicado pela Liga Ventures. Esses n\u00fameros refletem a urg\u00eancia de a\u00e7\u00f5es voltadas para a equidade de g\u00eanero e diversidade racial nesse segmento.<\/p>\n<p>O prazo para o cumprimento dessas metas \u00e9 igual ao tempo de dura\u00e7\u00e3o do fundo: 10 anos. Jos\u00e9 Manuel Barbosa, vice-presidente de Novos Neg\u00f3cios da Natura, refor\u00e7a o compromisso da empresa com essa transforma\u00e7\u00e3o estrutural. \u201cA diversidade \u00e9 essencial para a inova\u00e7\u00e3o. Acreditamos que apoiar as startups de hoje \u00e9 criar os l\u00edderes de amanh\u00e3, promovendo um ecossistema de neg\u00f3cios mais equilibrado\u201d, diz.<\/p>\n<p>Embora o objetivo do Natura Ventures seja investir em empresas que atendam a essas ambi\u00e7\u00f5es de diversidade, as startups tamb\u00e9m recebem apoio cont\u00ednuo para evoluir em sua jornada. \u201cEntendemos que muitas startups podem n\u00e3o estar completamente prontas para adotar essas pr\u00e1ticas desde o in\u00edcio, mas nosso apoio ser\u00e1 constante para ajud\u00e1-las a construir um caminho s\u00f3lido e alinhado aos nossos compromissos de impacto social e ambiental\u201d, explica Barbosa.<\/p>\n<p><strong>Iniciativas para a regenera\u00e7\u00e3o e impacto ambiental<\/strong><\/p>\n<p>Al\u00e9m de sua abordagem inclusiva, o Natura Ventures tem como objetivo impulsionar solu\u00e7\u00f5es regenerativas que v\u00e3o ao encontro da crise clim\u00e1tica global. O olhar para circularidade e regenera\u00e7\u00e3o busca apoiar startups que desenvolvam solu\u00e7\u00f5es alinhadas \u00e0 bioeconomia, principalmente com \u00eanfase na Amaz\u00f4nia e tecnologias que contribuam para uma economia de baixo carbono.<\/p>\n<p>\u201cEstamos comprometidos com a regenera\u00e7\u00e3o ambiental, e buscamos investimentos que n\u00e3o apenas cres\u00e7am de forma exponencial, mas que tamb\u00e9m tragam solu\u00e7\u00f5es reais para os desafios ambientais que enfrentamos. A prote\u00e7\u00e3o da Amaz\u00f4nia e a sustentabilidade da cadeia de suprimentos s\u00e3o prioridades para n\u00f3s\u201d, afirma o executivo.<\/p>\n<p>O fundo j\u00e1 realizou seu primeiro investimento no setor de log\u00edstica, com a startup Abbiamo, especializada em otimizar a log\u00edstica \u201clast mile\u201d e melhorar a experi\u00eancia de entrega ao consumidor. A parceria com a Abbiamo \u00e9 apenas o come\u00e7o de uma jornada que busca fortalecer a rela\u00e7\u00e3o da Natura com as startups e impulsionar sua miss\u00e3o de regenera\u00e7\u00e3o e inclus\u00e3o.<\/p>\n<p>\u00c0 medida que o Natura Ventures cresce e novos aportes s\u00e3o realizados, as expectativas s\u00e3o altas: n\u00e3o apenas para o sucesso financeiro, mas tamb\u00e9m para a transforma\u00e7\u00e3o das din\u00e2micas sociais e ambientais.<\/p>\n<p><strong>Sobre a Natura<\/strong><\/p>\n<p>Fundada em 1969, a Natura \u00e9 uma multinacional brasileira, l\u00edder em beleza e cuidados pessoais na Am\u00e9rica Latina. Conta com 3,5 milh\u00f5es de Consultoras na Am\u00e9rica Latina, sendo l\u00edder no setor de venda direta no Brasil.\u00a0Foi a primeira companhia de capital aberto a receber a certifica\u00e7\u00e3o de empresa B no mundo, em dezembro de 2014, o que refor\u00e7a sua atua\u00e7\u00e3o transparente e sustent\u00e1vel nos aspectos social, ambiental e econ\u00f4mico. \u00c9 tamb\u00e9m a primeira empresa brasileira a conquistar o selo &#8220;The Leaping Bunny&#8221;, concedido pela organiza\u00e7\u00e3o de prote\u00e7\u00e3o animal Cruelty Free International, em 2018, que atesta o compromisso da empresa com a n\u00e3o realiza\u00e7\u00e3o de testes em animais de seus produtos ou ingredientes. Com opera\u00e7\u00f5es na Argentina, Chile, Col\u00f4mbia, Equador, Estados Unidos, Fran\u00e7a, M\u00e9xico e Peru, os produtos da marca Natura podem ser adquiridos com as Consultoras, por meio do e-commerce, app Natura, nas lojas pr\u00f3prias ou nas franquias &#8220;Aqui tem Natura&#8221;. Para mais informa\u00e7\u00f5es, visite\u00a0<a href=\"https:\/\/urldefense.com\/v3\/__http:\/www.natura.com.br\/__;!!N96JrnIq8IfO5w!hgHiajSlYAJHTxBAmLvVA6k3tNYFH2bGAQnSV8InhuGFWfYfb3O7EIHwczaYdetgi3M0K6mC6TZJRBaTqNE2SAYz4vMYmbmR$\">www.natura.com.br<\/a>\u00a0 ou acesse os perfis da empresa nas redes sociais:\u00a0<a href=\"https:\/\/urldefense.com\/v3\/__https:\/nsa.i-mpressmta.com\/link.php?code=bDpodHRwJTNBJTJGJTJGd3d3LmxpbmtlZGluLmNvbSUyRmNvbXBhbnklMkZuYXR1cmE6NDEyNDIzMDg4NTpsaWdpYS5uZWl2YUBjb250ZXVkb25ldC5jb206NjhjZGZj__;!!N96JrnIq8IfO5w!hgHiajSlYAJHTxBAmLvVA6k3tNYFH2bGAQnSV8InhuGFWfYfb3O7EIHwczaYdetgi3M0K6mC6TZJRBaTqNE2SAYz4usPktqh$\">LinkedIn<\/a>,\u00a0<a href=\"https:\/\/urldefense.com\/v3\/__https:\/nsa.i-mpressmta.com\/link.php?code=bDpodHRwJTNBJTJGJTJGd3d3LmZhY2Vib29rLmNvbSUyRm5hdHVyYWJyb2ZpY2lhbDo0MTI0MjMwODg1OmxpZ2lhLm5laXZhQGNvbnRldWRvbmV0LmNvbTo4YzQ5ODg=__;!!N96JrnIq8IfO5w!hgHiajSlYAJHTxBAmLvVA6k3tNYFH2bGAQnSV8InhuGFWfYfb3O7EIHwczaYdetgi3M0K6mC6TZJRBaTqNE2SAYz4kSot_6X$\">Facebook<\/a>\u00a0e\u00a0<a href=\"https:\/\/urldefense.com\/v3\/__https:\/nsa.i-mpressmta.com\/link.php?code=bDpodHRwJTNBJTJGJTJGd3d3Lmluc3RhZ3JhbS5jb20lMkZuYXR1cmFicm9maWNpYWwlMkY6NDEyNDIzMDg4NTpsaWdpYS5uZWl2YUBjb250ZXVkb25ldC5jb206MTg1NDMz__;!!N96JrnIq8IfO5w!hgHiajSlYAJHTxBAmLvVA6k3tNYFH2bGAQnSV8InhuGFWfYfb3O7EIHwczaYdetgi3M0K6mC6TZJRBaTqNE2SAYz4tGOH7t-$\">Instagram<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Empresa estabelece ambi\u00e7\u00f5es e assume o compromisso de investir, por meio do fundo Natura Ventures, em startups lideradas por mulheres, pessoas negras e com diversidade geogr\u00e1fica, al\u00e9m de apoiar solu\u00e7\u00f5es regenerativas \u00a0A Natura, marca l\u00edder em beleza e cuidados pessoais na Am\u00e9rica Latina, est\u00e1 ampliando seus esfor\u00e7os para construir um futuro mais inclusivo e sustent\u00e1vel. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18962,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[51,54,56,57,60,62],"tags":[11062],"featured_image_src":{"landsacpe":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/06\/Jose-Manuel-Natura-1140x445.jpg",1140,445,true],"list":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/06\/Jose-Manuel-Natura-463x348.jpg",463,348,true],"medium":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/06\/Jose-Manuel-Natura-300x200.jpg",300,200,true],"full":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/06\/Jose-Manuel-Natura-scaled.jpg",2560,1708,false]},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/06\/Jose-Manuel-Natura-scaled.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/18961"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/comments?post=18961"}],"version-history":[{"count":1,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/18961\/revisions"}],"predecessor-version":[{"id":18963,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/18961\/revisions\/18963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media\/18962"}],"wp:attachment":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media?parent=18961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/categories?post=18961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags?post=18961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}