{"id":17877,"date":"2025-04-27T18:06:11","date_gmt":"2025-04-27T21:06:11","guid":{"rendered":"https:\/\/revistaempresarios.net\/web\/?p=17877"},"modified":"2025-04-27T18:06:11","modified_gmt":"2025-04-27T21:06:11","slug":"28-de-abril-dia-mundial-da-seguranca-e-saude-no-trabalho-inovacao-aprimora-a-seguranca-dos-trabalhadores-com-asfalto-por-wagner-cizotto-junior-e-sergio-alves-da-silva-junior","status":"publish","type":"post","link":"https:\/\/revistaempresarios.net\/web\/2025\/04\/27\/28-de-abril-dia-mundial-da-seguranca-e-saude-no-trabalho-inovacao-aprimora-a-seguranca-dos-trabalhadores-com-asfalto-por-wagner-cizotto-junior-e-sergio-alves-da-silva-junior\/","title":{"rendered":"28 de abril: Dia Mundial da Seguran\u00e7a e Sa\u00fade no Trabalho &#8211; Inova\u00e7\u00e3o aprimora a seguran\u00e7a dos trabalhadores com asfalto  &#8211; Por: Wagner Cizotto Junior e Sergio Alves da Silva Junior"},"content":{"rendered":"<p>De que forma as novas tecnologias est\u00e3o garantindo um ambiente de trabalho mais seguro no setor de constru\u00e7\u00e3o? O ano come\u00e7ou com boas perspectivas para o setor de infraestrutura com proje\u00e7\u00f5es de crescimento e investimentos anunciados na melhoria da infraestrutura log\u00edstica do Brasil. Segundo a C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), h\u00e1 expectativa de crescimento de 3,5% no setor neste ano, o que refor\u00e7a a necessidade de um compromisso cont\u00ednuo com ambientes de trabalho mais seguros e saud\u00e1veis.<\/p>\n<p>A constru\u00e7\u00e3o e manuten\u00e7\u00e3o de estradas traz a necessidade de trabalhar diariamente com asfalto, um material essencial, mas que exige cuidados espec\u00edficos devido aos riscos inerentes \u00e0 sua manipula\u00e7\u00e3o. A exposi\u00e7\u00e3o prolongada a vapores e contato direto com o asfalto quente podem causar riscos \u00e0 sa\u00fade dos trabalhadores, desde problemas respirat\u00f3rios at\u00e9 irrita\u00e7\u00f5es na pele e doen\u00e7as graves a longo prazo.<\/p>\n<p>Nesse contexto, a ci\u00eancia e a qu\u00edmica se tornam grandes aliadas, porque melhoram as pr\u00e1ticas a partir de solu\u00e7\u00f5es inovadoras. Um exemplo disso \u00e9 o aditivo polim\u00e9rico de alta performance, B2Last\u00ae, que modifica as propriedades do asfalto e, potencialmente, ajuda a reduzir alguns dos riscos associados ao seu uso, trazendo benef\u00edcios diretos para a sa\u00fade e seguran\u00e7a dos trabalhadores.<\/p>\n<p>Uma das principais vantagens do aditivo \u00e9 a sua capacidade de reduzir significativamente a emiss\u00e3o de vapores org\u00e2nicos vol\u00e1teis (VOCs) durante a aplica\u00e7\u00e3o do asfalto. A produ\u00e7\u00e3o de asfalto morno com B2Last\u00ae permite temperaturas abaixo de 140\u00b0C, diminuindo at\u00e9 65% a emiss\u00e3o de vapores de betume, o que minimiza os riscos respirat\u00f3rios e melhora a sa\u00fade no ambiente de trabalho.<\/p>\n<p>Al\u00e9m disso, a solu\u00e7\u00e3o facilita a aplica\u00e7\u00e3o do asfalto, tornando-o mais male\u00e1vel e reduzindo a necessidade de altas temperaturas, o que diminui os riscos de queimaduras e outros acidentes com o material quente. Ele ainda aumenta a resist\u00eancia e a elasticidade do asfalto, prolongando a vida \u00fatil da estrada. Consequentemente, tamb\u00e9m contribui para a redu\u00e7\u00e3o da frequ\u00eancia de manuten\u00e7\u00e3o e reparos nas estradas, o que significa menos exposi\u00e7\u00e3o aos riscos que fazem parte dessas atividades.<\/p>\n<p>A BASF prioriza a seguran\u00e7a em todas as etapas do ciclo de vida do B2Last\u00ae, desde a produ\u00e7\u00e3o at\u00e9 a aplica\u00e7\u00e3o. Apesar do uso do aditivo n\u00e3o exigir nenhum equipamento de prote\u00e7\u00e3o adicional, a empresa disponibiliza informa\u00e7\u00f5es detalhadas sobre o manuseio seguro do produto para garantir a prote\u00e7\u00e3o dos trabalhadores.<\/p>\n<p>Ao investir em tecnologias que reduzem os riscos e promovem o bem-estar dos trabalhadores e a sustentabilidade, estamos apoiando a transi\u00e7\u00e3o verde da cadeia produtiva do asfalto. Essa transforma\u00e7\u00e3o n\u00e3o s\u00f3 beneficia a sa\u00fade dos profissionais, mas tamb\u00e9m alinha a ind\u00fastria com as demandas globais por pr\u00e1ticas mais respons\u00e1veis e ecol\u00f3gicas. O aditivo \u00e9 um exemplo claro de como a inova\u00e7\u00e3o pode ser utilizada para proteger a sa\u00fade e a seguran\u00e7a dos profissionais que constroem e mant\u00eam a infraestrutura essencial para o nosso desenvolvimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De que forma as novas tecnologias est\u00e3o garantindo um ambiente de trabalho mais seguro no setor de constru\u00e7\u00e3o? O ano come\u00e7ou com boas perspectivas para o setor de infraestrutura com proje\u00e7\u00f5es de crescimento e investimentos anunciados na melhoria da infraestrutura log\u00edstica do Brasil. Segundo a C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), h\u00e1 expectativa de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[51,57,60],"tags":[10598,10597],"featured_image_src":{"landsacpe":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/04\/b8ce15545296ba9085597677b65f85e1_XL-1140x445.jpg",1140,445,true],"list":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/04\/b8ce15545296ba9085597677b65f85e1_XL-463x348.jpg",463,348,true],"medium":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/04\/b8ce15545296ba9085597677b65f85e1_XL-300x200.jpg",300,200,true],"full":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/04\/b8ce15545296ba9085597677b65f85e1_XL.jpg",1220,813,false]},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2025\/04\/b8ce15545296ba9085597677b65f85e1_XL.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/17877"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/comments?post=17877"}],"version-history":[{"count":1,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/17877\/revisions"}],"predecessor-version":[{"id":17879,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/17877\/revisions\/17879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media\/17878"}],"wp:attachment":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media?parent=17877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/categories?post=17877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags?post=17877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}