{"id":15045,"date":"2024-04-25T12:09:20","date_gmt":"2024-04-25T15:09:20","guid":{"rendered":"https:\/\/revistaempresarios.net\/web\/?p=15045"},"modified":"2024-04-25T12:09:20","modified_gmt":"2024-04-25T15:09:20","slug":"brasil-e-o-segundo-pais-mais-entusiasmado-com-os-potenciais-da-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/revistaempresarios.net\/web\/2024\/04\/25\/brasil-e-o-segundo-pais-mais-entusiasmado-com-os-potenciais-da-inteligencia-artificial\/","title":{"rendered":"Brasil \u00e9 o segundo pa\u00eds mais entusiasmado com os potenciais da Intelig\u00eancia Artificial"},"content":{"rendered":"<p>O Brasil \u00e9 o segundo pa\u00eds mais entusiasmado com os potenciais da Intelig\u00eancia Artificial (IA), de acordo com o levantamento \u201c<a href=\"https:\/\/www.thoughtworks.com\/pt-br\/insights\/reports\/genai-what-consumers-want\" target=\"_blank\" rel=\"noopener\">IA Generativa: o que os consumidores desejam<\/a>\u201d realizado pela consultoria Thoughtworks\u00a0com 10 mil pessoas em 10 pa\u00edses pelo mundo.<\/p>\n<p>Entre as raz\u00f5es para toda essa anima\u00e7\u00e3o com a tecnologia est\u00e3o a efici\u00eancia operacional e a rentabilidade que ela traz para os neg\u00f3cios. Em um estudo conduzido pela McKinsey foi estimado que a IA generativa pode adicionar entre US$ 2,6 trilh\u00f5es e US$ 4,4 trilh\u00f5es em valor anual \u00e0s empresas, e o relat\u00f3rio \u201cEstado da IA na organiza\u00e7\u00e3o\u201d, realizado pela Deloitte em 2022, com mais de 2.600 l\u00edderes, constatou que 94% deles acreditam que a IA pode transformar o setor nos pr\u00f3ximos anos.<\/p>\n<p>\u201c\u00c9 importante identificar o que tem causado essa esp\u00e9cie de subaproveitamento da IA, ou seja, o que pode estar errado no plano de a\u00e7\u00e3o. Do contr\u00e1rio, corremos o risco de aumentarmos a dist\u00e2ncia entre quem j\u00e1 vivencia os benef\u00edcios com mais plenitude e quem ainda est\u00e1 se esfor\u00e7ando para isso\u201d, afirma Edgar Garcia, vice-presidente da UiPath para a Am\u00e9rica Latina.<\/p>\n<div id=\"merca-358989424\" class=\"merca-home-e-meio-materias\">\n<div id=\"merca-1589810573\" class=\"merca-target\" data-merca-trackid=\"149015\" data-merca-trackbid=\"1\">Muitas empresas ainda encontram dificuldades para progredir em suas agendas de automa\u00e7\u00e3o e IA. O relat\u00f3rio da Deloitte estima que 74% das <a href=\"https:\/\/mercadoeconsumo.com.br\/12\/04\/2024\/tecnologia\/sete-em-cada-dez-executivos-consideram-a-adocao-da-ia-generativa-como-prioridade\/\">lideran\u00e7as<\/a>\u00a0consultadas ainda n\u00e3o conseguem capturar retorno, ou valor suficiente, das a\u00e7\u00f5es em Intelig\u00eancia Artificial j\u00e1 implementadas.<\/div>\n<\/div>\n<p>A falta de experi\u00eancia e conhecimento sobre a Intelig\u00eancia Artificial deixa muitos executivos apreensivos e inseguros para o ganho de escala no uso da IA, segundo o \u00cdndice Global de Ado\u00e7\u00e3o de IA da IBM 2023.<\/p>\n<p><strong>Com informa\u00e7\u00f5es de Mercado&amp;Tech.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil \u00e9 o segundo pa\u00eds mais entusiasmado com os potenciais da Intelig\u00eancia Artificial (IA), de acordo com o levantamento \u201cIA Generativa: o que os consumidores desejam\u201d realizado pela consultoria Thoughtworks\u00a0com 10 mil pessoas em 10 pa\u00edses pelo mundo. Entre as raz\u00f5es para toda essa anima\u00e7\u00e3o com a tecnologia est\u00e3o a efici\u00eancia operacional e a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[51,54,56,57,60,62],"tags":[9510],"featured_image_src":{"landsacpe":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2024\/04\/shutterstock_2276290857-1000x445.jpg",1000,445,true],"list":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2024\/04\/shutterstock_2276290857-463x348.jpg",463,348,true],"medium":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2024\/04\/shutterstock_2276290857-300x149.jpg",300,149,true],"full":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2024\/04\/shutterstock_2276290857.jpg",1000,497,false]},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2024\/04\/shutterstock_2276290857.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/15045"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/comments?post=15045"}],"version-history":[{"count":1,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/15045\/revisions"}],"predecessor-version":[{"id":15047,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/15045\/revisions\/15047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media\/15046"}],"wp:attachment":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media?parent=15045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/categories?post=15045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags?post=15045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}