{"id":11425,"date":"2023-08-08T17:39:21","date_gmt":"2023-08-08T20:39:21","guid":{"rendered":"https:\/\/revistaempresarios.net\/web\/?p=11425"},"modified":"2023-08-08T17:39:34","modified_gmt":"2023-08-08T20:39:34","slug":"no-conarh-2023-espro-mostra-como-a-inclusao-de-jovens-no-mercado-de-trabalho-pode-compor-a-agenda-esg-das-empresas","status":"publish","type":"post","link":"https:\/\/revistaempresarios.net\/web\/2023\/08\/08\/no-conarh-2023-espro-mostra-como-a-inclusao-de-jovens-no-mercado-de-trabalho-pode-compor-a-agenda-esg-das-empresas\/","title":{"rendered":"No CONARH 2023, Espro mostra como a inclus\u00e3o de jovens no mercado de trabalho pode compor a agenda ESG das empresas"},"content":{"rendered":"<p><em>Associa\u00e7\u00e3o filantr\u00f3pica, refer\u00eancia em impacto social para jovens em vulnerabilidade, fornece solu\u00e7\u00f5es personalizadas para empresas comprometidas com a causa <\/em><\/p>\n<p>O Espro (Ensino Social Profissionalizante), associa\u00e7\u00e3o filantr\u00f3pica que atua h\u00e1 mais de 40 anos na inser\u00e7\u00e3o de adolescentes e jovens em vulnerabilidade social no mundo do trabalho, vai mostrar no CONARH 2023 toda a sua experi\u00eancia em parcerias com o setor privado no campo da socioaprendizagem, bem como a capacidade de fornecer solu\u00e7\u00f5es personalizadas voltadas ao ESG. A 49<sup>a<\/sup> edi\u00e7\u00e3o do evento, considerado o maior na \u00e1rea de gest\u00e3o de pessoas na Am\u00e9rica Latina, acontece de 08 a 10 de agosto no S\u00e3o Paulo Expo.<\/p>\n<p>Em seu estande, o Espro destaca os projetos e recursos ao alcance das empresas parceiras, sempre priorizando o combate \u00e0s desigualdades e a prote\u00e7\u00e3o dos direitos dos adolescentes e jovens, para que eles possam alcan\u00e7ar emprego pleno, produtivo e decente, al\u00e9m de compet\u00eancias, habilidades e viv\u00eancias que os permitam se tornar protagonistas de suas vidas e carreiras.<\/p>\n<p>Outro objetivo da participa\u00e7\u00e3o da entidade no evento \u00e9 difundir no setor privado a ideia de que a socioaprendizagem pode compor agendas de ESG, em que a interven\u00e7\u00e3o social \u00e9 a mola propulsora do desdobramento nos dois outros pilares: ambiental e governan\u00e7a.<\/p>\n<p>\u201cO impacto social por meio da capacita\u00e7\u00e3o e inclus\u00e3o produtiva no mercado de trabalho permite que as empresas contribuam com a diminui\u00e7\u00e3o das desigualdades nas localidades onde atuam, al\u00e9m de garantir a sustentabilidade dos neg\u00f3cios e, claro, do planeta. O Espro \u00e9 refer\u00eancia na constru\u00e7\u00e3o de solu\u00e7\u00f5es personalizadas para o atendimento da agenda ESG das empresas, sempre buscando estimular o pensamento cr\u00edtico e a capacidade criativa dos jovens para o despertar de cidad\u00e3os conscientes e atuantes nas comunidades onde vivem. Acredito que estamos no caminho certo pois, das 69 empresas que figuram na primeira lista ISE (\u00cdndice de Sustentabilidade Empresarial da B3) de 2023, 42 (61%) s\u00e3o parceiras do Espro\u201d, afirma Alessandro Saade, superintendente executivo do Espro.<\/p>\n<p><strong>Sobre o Espro<\/strong><\/p>\n<p>O Espro (Ensino Social Profissionalizante) atua na inser\u00e7\u00e3o de adolescentes e jovens em vulnerabilidade social no mundo do trabalho, por meio da socioaprendizagem, oferecendo uma extensa <a href=\"https:\/\/www.espro.org.br\/seja-um-jovem-espro\/\">jornada<\/a> gratuita, que come\u00e7a nos Projetos de Forma\u00e7\u00e3o para o Mundo do Trabalho (patrocinados ou personalizados para nossos parceiros) e segue no Programa de Aprendizagem Profissional ou no Programa de Est\u00e1gio. Dessa forma, a entidade cumpre cinco dos 17 objetivos de desenvolvimento sustent\u00e1vel da ONU: trabalho decente e crescimento econ\u00f4mico, redu\u00e7\u00e3o das desigualdades, educa\u00e7\u00e3o de qualidade, sa\u00fade e bem-estar e erradica\u00e7\u00e3o da pobreza.<\/p>\n<p>O objetivo principal do Espro \u00e9 permitir aos jovens do Brasil desenvolver seus talentos para que assumam o protagonismo da constru\u00e7\u00e3o do seu futuro e de uma sociedade mais inclusiva, bem como apoiar suas fam\u00edlias e comunidades, seja por meio de projetos de capacita\u00e7\u00e3o ou assist\u00eancia social.<\/p>\n<p>Em 44 anos de exist\u00eancia, a entidade, que atua em \u00e2mbito nacional, encaminhou 521 mil jovens para sua primeira oportunidade de emprego e realizou 1,1 milh\u00e3o de atendimentos sociais, englobando visitas domiciliares, acompanhamentos psicol\u00f3gicos, visitas t\u00e9cnicas, oficinas de gera\u00e7\u00e3o de renda, encaminhamentos para a rede de apoio e outras iniciativas para desenvolver e melhorar a vida e o ambiente na jornada destes jovens e das comunidades onde vivem.<\/p>\n<p>As <a href=\"https:\/\/www.espro.org.br\/empresas\/seja-uma-empresa-parceira\/\">empresas e parceiros<\/a> do Espro t\u00eam acesso a um portf\u00f3lio completo de solu\u00e7\u00f5es de recrutamento de jovens com a finalidade de transformar a sociedade por meio de projetos de impacto social idealizados para cada uma de suas necessidades.<\/p>\n<p>O Espro tem 8 filiais e 50 n\u00facleos regionais espalhados pelo Brasil, alcan\u00e7ando 992 munic\u00edpios, capacitando anualmente mais de 25 mil jovens por meio dos programas e projetos. Para ampliar sua capilaridade nacional, a entidade criou a Rede de Aprendizagem Espro (RAE) que estabelece alian\u00e7as com outras organiza\u00e7\u00f5es para fazer o acolhimento dos jovens de forma colaborativa, por meio do seu Sistema de Aprendizagem (SAE).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Associa\u00e7\u00e3o filantr\u00f3pica, refer\u00eancia em impacto social para jovens em vulnerabilidade, fornece solu\u00e7\u00f5es personalizadas para empresas comprometidas com a causa O Espro (Ensino Social Profissionalizante), associa\u00e7\u00e3o filantr\u00f3pica que atua h\u00e1 mais de 40 anos na inser\u00e7\u00e3o de adolescentes e jovens em vulnerabilidade social no mundo do trabalho, vai mostrar no CONARH 2023 toda a sua experi\u00eancia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[51,56,57,58,60],"tags":[8215,8214],"featured_image_src":{"landsacpe":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/08\/6b678932-6398-4295-b12c-35b8a348a1c9-643x445.jpg",643,445,true],"list":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/08\/6b678932-6398-4295-b12c-35b8a348a1c9-463x348.jpg",463,348,true],"medium":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/08\/6b678932-6398-4295-b12c-35b8a348a1c9-300x287.jpg",300,287,true],"full":["https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/08\/6b678932-6398-4295-b12c-35b8a348a1c9.jpg",643,615,false]},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/revistaempresarios.net\/web\/wp-content\/uploads\/2023\/08\/6b678932-6398-4295-b12c-35b8a348a1c9.jpg","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/11425"}],"collection":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/comments?post=11425"}],"version-history":[{"count":1,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/11425\/revisions"}],"predecessor-version":[{"id":11427,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/posts\/11425\/revisions\/11427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media\/11426"}],"wp:attachment":[{"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/media?parent=11425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/categories?post=11425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaempresarios.net\/web\/wp-json\/wp\/v2\/tags?post=11425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}